{"id":1133,"date":"2024-04-08T12:27:50","date_gmt":"2024-04-08T10:27:50","guid":{"rendered":"https:\/\/elnasl.eu\/?page_id=1133"},"modified":"2025-02-20T13:50:02","modified_gmt":"2025-02-20T12:50:02","slug":"maquinaria","status":"publish","type":"page","link":"https:\/\/elnasl.eu\/fr\/maquinaria","title":{"rendered":"Technologie"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"1133\" class=\"elementor elementor-1133\" data-elementor-post-type=\"page\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55f1120 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55f1120\" data-element_type=\"section\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t\t\t<div class=\"elementor-background-overlay\"><\/div>\n\t\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-no\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-b229dc8\" data-id=\"b229dc8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-95aaace elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"95aaace\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h1 class=\"elementor-heading-title elementor-size-default\">Nos machines<\/h1>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-55196bb e-flex e-con-boxed e-con e-parent\" data-id=\"55196bb\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-1b6832c elementor-widget elementor-widget-text-editor\" data-id=\"1b6832c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chez Electroerosiones Navarra, nous accordons une grande importance au parc technologique afin de fournir un service efficace et de qualit\u00e9, garantissant une innovation constante et une adaptabilit\u00e9 aux besoins de nos clients.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-55f522e elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"55f522e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-82ddbbd\" data-id=\"82ddbbd\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-ecc246c elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"ecc246c\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-07cff14 elementor-invisible\" data-id=\"07cff14\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-24f7117 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"24f7117\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img fetchpriority=\"high\" decoding=\"async\" width=\"1050\" height=\"994\" src=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI510P_RVB_HR-1.webp\" class=\"attachment-full size-full wp-image-1210\" alt=\"ROBOFIL 510P\u200b\" srcset=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI510P_RVB_HR-1.webp 1050w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI510P_RVB_HR-1-300x284.webp 300w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI510P_RVB_HR-1-1024x969.webp 1024w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI510P_RVB_HR-1-768x727.webp 768w\" sizes=\"(max-width: 1050px) 100vw, 1050px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-155ae46 elementor-widget elementor-widget-heading\" data-id=\"155ae46\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ROBOFIL 510P\u200b<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-9a41507 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"9a41507\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/elnasl.eu\/fr\/robofil-510p\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-53578fd elementor-invisible\" data-id=\"53578fd\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-4927749 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"4927749\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1050\" height=\"994\" src=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI-440-P.jpg.webp.webp\" class=\"attachment-full size-full wp-image-1219\" alt=\"ROBOFIL 440P\" srcset=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI-440-P.jpg.webp.webp 1050w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI-440-P.jpg.webp-300x284.webp 300w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI-440-P.jpg.webp-1024x969.webp 1024w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI-440-P.jpg.webp-768x727.webp 768w\" sizes=\"(max-width: 1050px) 100vw, 1050px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-c34167b elementor-widget elementor-widget-heading\" data-id=\"c34167b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ROBOFIL 440P<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e320ded elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"e320ded\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/elnasl.eu\/fr\/robofil-440p\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-bf68ae1 elementor-invisible\" data-id=\"bf68ae1\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-52b782f elementor-invisible elementor-widget elementor-widget-image\" data-id=\"52b782f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img decoding=\"async\" width=\"1050\" height=\"994\" src=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/CUT-300-2.webp.webp\" class=\"attachment-full size-full wp-image-1228\" alt=\"\" srcset=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/CUT-300-2.webp.webp 1050w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/CUT-300-2.webp-300x284.webp 300w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/CUT-300-2.webp-1024x969.webp 1024w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/CUT-300-2.webp-768x727.webp 768w\" sizes=\"(max-width: 1050px) 100vw, 1050px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b61d28b elementor-widget elementor-widget-heading\" data-id=\"b61d28b\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">COUPE 300 MS<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-490283f elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"490283f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/elnasl.eu\/fr\/cut-300-ms\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-b149480 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"b149480\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-c0fccbf elementor-invisible\" data-id=\"c0fccbf\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-84c2580 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"84c2580\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1050\" height=\"994\" src=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/CUT-E350-1.jpg.png\" class=\"attachment-full size-full wp-image-1232\" alt=\"CUT E350\u200b\u200b\" srcset=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/CUT-E350-1.jpg.png 1050w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/CUT-E350-1.jpg-300x284.png 300w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/CUT-E350-1.jpg-1024x969.png 1024w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/CUT-E350-1.jpg-768x727.png 768w\" sizes=\"(max-width: 1050px) 100vw, 1050px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a6b275c elementor-widget elementor-widget-heading\" data-id=\"a6b275c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">COUPE E350<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d20e01e elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"d20e01e\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/elnasl.eu\/fr\/cut-e350\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-de31972 elementor-invisible\" data-id=\"de31972\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9871bb0 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"9871bb0\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1050\" height=\"994\" src=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/qx3f-ona-electroerosion-1200x1200-1-1.jpg.png\" class=\"attachment-full size-full wp-image-1236\" alt=\"ONA QX3F\" srcset=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/qx3f-ona-electroerosion-1200x1200-1-1.jpg.png 1050w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/qx3f-ona-electroerosion-1200x1200-1-1.jpg-300x284.png 300w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/qx3f-ona-electroerosion-1200x1200-1-1.jpg-1024x969.png 1024w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/qx3f-ona-electroerosion-1200x1200-1-1.jpg-768x727.png 768w\" sizes=\"(max-width: 1050px) 100vw, 1050px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-a5f069c elementor-widget elementor-widget-heading\" data-id=\"a5f069c\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">ONA QX3F<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-22e4c03 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"22e4c03\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/elnasl.eu\/fr\/ona-qx3f\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-33 elementor-inner-column elementor-element elementor-element-68afb22 elementor-invisible\" data-id=\"68afb22\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-090c299 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"090c299\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1050\" height=\"994\" src=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/64c_2020-1.jpg.png\" class=\"attachment-2048x2048 size-2048x2048 wp-image-1240\" alt=\"STAR 64C\" srcset=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/64c_2020-1.jpg.png 1050w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/64c_2020-1.jpg-300x284.png 300w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/64c_2020-1.jpg-1024x969.png 1024w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/64c_2020-1.jpg-768x727.png 768w\" sizes=\"(max-width: 1050px) 100vw, 1050px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-f865313 elementor-widget elementor-widget-heading\" data-id=\"f865313\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h3 class=\"elementor-heading-title elementor-size-default\">\u00c9toile 64C<\/h3>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-1635f00 elementor-align-center elementor-invisible elementor-widget elementor-widget-button\" data-id=\"1635f00\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/elnasl.eu\/fr\/star-64c\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Voir plus<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-0f18f4b elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"0f18f4b\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-645ad04\" data-id=\"645ad04\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-06d9c6d elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"06d9c6d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-cd15e15 elementor-invisible\" data-id=\"cd15e15\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-5151fb3 elementor-widget elementor-widget-heading\" data-id=\"5151fb3\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Technologie de pointe pour un travail pr\u00e9cis<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-7f2743c elementor-widget elementor-widget-text-editor\" data-id=\"7f2743c\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chez Electroerosiones Navarra, nous nous distinguons par l&#039;utilisation d&#039;une technologie de pointe dans un travail de haute pr\u00e9cision pour garantir les meilleurs r\u00e9sultats.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-6ab25c8\" data-id=\"6ab25c8\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9da95d1 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"9da95d1\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/38-1024x576.jpg\" class=\"attachment-large size-large wp-image-2558\" alt=\"Beneficios del marcado l\u00e1ser en la industria moderna\" srcset=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/38-1024x576.jpg 1024w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/38-300x169.jpg 300w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/38-768x432.jpg 768w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/38-1536x864.jpg 1536w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/38.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-39be48e elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"39be48e\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-54ff534\" data-id=\"54ff534\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-78fe3e2 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"78fe3e2\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-8249f75 elementor-invisible\" data-id=\"8249f75\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9083d6d elementor-invisible elementor-widget elementor-widget-image\" data-id=\"9083d6d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/05\/34-1024x576.jpg\" class=\"attachment-large size-large wp-image-2835\" alt=\"\" srcset=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/05\/34-1024x576.jpg 1024w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/05\/34-300x169.jpg 300w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/05\/34-768x432.jpg 768w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/05\/34-1536x864.jpg 1536w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/05\/34.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-5e870e9\" data-id=\"5e870e9\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-ee5bcc4 elementor-widget elementor-widget-heading\" data-id=\"ee5bcc4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Technologie de pr\u00e9cision<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-29b9953 elementor-widget elementor-widget-text-editor\" data-id=\"29b9953\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous r\u00e9alisons des travaux pr\u00e9cis dans divers mat\u00e9riaux tels que l&#039;aluminium, l&#039;acier et le plastique, en nous adaptant toujours aux besoins sp\u00e9cifiques de chaque client.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-e0b4a2d elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"e0b4a2d\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-37fce8e\" data-id=\"37fce8e\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-9931409 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"9931409\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-a80b060 elementor-invisible\" data-id=\"a80b060\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-9007ef4 elementor-widget elementor-widget-heading\" data-id=\"9007ef4\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Innovation et pr\u00e9cision : notre approche<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-e5191bb elementor-widget elementor-widget-text-editor\" data-id=\"e5191bb\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Nous utilisons des machines de pointe et impliquons une \u00e9quipe hautement qualifi\u00e9e pour garantir une qualit\u00e9 et une efficacit\u00e9 maximales dans chaque projet.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-fe78a11\" data-id=\"fe78a11\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-2806ea6 elementor-invisible elementor-widget elementor-widget-image\" data-id=\"2806ea6\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/9-1-1024x576.webp\" class=\"attachment-large size-large wp-image-1853\" alt=\"Nuestra Misi\u00f3n - Electroerosiones\" srcset=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/9-1-1024x576.webp 1024w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/9-1-300x169.webp 300w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/9-1-768x432.webp 768w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/9-1-1536x864.webp 1536w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/9-1.webp 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-fea0970 elementor-hidden-desktop elementor-hidden-tablet elementor-hidden-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"fea0970\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-ab85a1a\" data-id=\"ab85a1a\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-inner-section elementor-element elementor-element-f1efd34 elementor-reverse-tablet elementor-reverse-mobile elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"f1efd34\" data-element_type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-d3cea51 elementor-invisible\" data-id=\"d3cea51\" data-element_type=\"column\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-cfb359d elementor-invisible elementor-widget elementor-widget-image\" data-id=\"cfb359d\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/19-1024x576.jpg\" class=\"attachment-large size-large wp-image-2326\" alt=\"Tecnolog\u00eda precisa\" srcset=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/19-1024x576.jpg 1024w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/19-300x169.jpg 300w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/19-768x432.jpg 768w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/19-1536x864.jpg 1536w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/19.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-inner-column elementor-element elementor-element-63bbecf\" data-id=\"63bbecf\" data-element_type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-b6a9703 elementor-widget elementor-widget-heading\" data-id=\"b6a9703\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Qualit\u00e9 assur\u00e9e : r\u00e9sultats pr\u00e9cis<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-b947ced elementor-widget elementor-widget-text-editor\" data-id=\"b947ced\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Notre technologie nous permet de r\u00e9pondre aux normes les plus exigeantes, en obtenant des ajustements impeccables et des r\u00e9sultats constants de haute qualit\u00e9.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t<div class=\"elementor-element elementor-element-de955e5 e-flex e-con-boxed e-con e-parent\" data-id=\"de955e5\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-eec19ce elementor-invisible elementor-widget elementor-widget-heading\" data-id=\"eec19ce\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeIn&quot;}\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Machines compl\u00e9mentaires\n<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-e0d6b00 e-con-full e-flex e-con e-child\" data-id=\"e0d6b00\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-a8f1af4 e-grid e-con-boxed e-con e-child\" data-id=\"a8f1af4\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-626dbe5 elementor-widget elementor-widget-image\" data-id=\"626dbe5\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/01\/Diseno-sin-titulo-3-1024x576.jpg\" class=\"attachment-large size-large wp-image-3961\" alt=\"\" srcset=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/01\/Diseno-sin-titulo-3-1024x576.jpg 1024w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/01\/Diseno-sin-titulo-3-300x169.jpg 300w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/01\/Diseno-sin-titulo-3-768x432.jpg 768w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/01\/Diseno-sin-titulo-3-1536x864.jpg 1536w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/01\/Diseno-sin-titulo-3-18x10.jpg 18w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/01\/Diseno-sin-titulo-3.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-4229a91 elementor-widget elementor-widget-image\" data-id=\"4229a91\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/11\/tridimensional-1024x576.jpg\" class=\"attachment-large size-large wp-image-3683\" alt=\"\" srcset=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/11\/tridimensional-1024x576.jpg 1024w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/11\/tridimensional-300x169.jpg 300w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/11\/tridimensional-768x432.jpg 768w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/11\/tridimensional-1536x864.jpg 1536w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/11\/tridimensional-18x10.jpg 18w, https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/11\/tridimensional.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dab437f elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"dab437f\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tMachine de marquage laser\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t Permet des gravures durables et haute d\u00e9finition sur une grande vari\u00e9t\u00e9 de mat\u00e9riaux.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-dbae9e8 elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"dbae9e8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tTridimensionnel\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\t\u00c9quipement cl\u00e9 pour r\u00e9aliser des mesures pr\u00e9cises et v\u00e9rifier la qualit\u00e9 des pi\u00e8ces produites.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-5520cb4 e-con-full e-flex e-con e-child\" data-id=\"5520cb4\" data-element_type=\"container\">\n\t\t<div class=\"elementor-element elementor-element-57cf079 e-grid e-con-boxed e-con e-child\" data-id=\"57cf079\" data-element_type=\"container\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t\t\t<div class=\"elementor-element elementor-element-9e78053 elementor-widget elementor-widget-image\" data-id=\"9e78053\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/1-1024x576.jpg\" class=\"attachment-large size-large wp-image-4145\" alt=\"\" srcset=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/1-1024x576.jpg 1024w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/1-300x169.jpg 300w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/1-768x432.jpg 768w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/1-1536x864.jpg 1536w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/1-18x10.jpg 18w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/1.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-2c7847c elementor-widget elementor-widget-image\" data-id=\"2c7847c\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"450\" src=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/Diseno-sin-titulo-5-1024x576.jpg\" class=\"attachment-large size-large wp-image-4242\" alt=\"\" srcset=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/Diseno-sin-titulo-5-1024x576.jpg 1024w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/Diseno-sin-titulo-5-300x169.jpg 300w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/Diseno-sin-titulo-5-768x432.jpg 768w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/Diseno-sin-titulo-5-1536x864.jpg 1536w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/Diseno-sin-titulo-5-18x10.jpg 18w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/Diseno-sin-titulo-5.jpg 1920w\" sizes=\"(max-width: 800px) 100vw, 800px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-d89e2f8 elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"d89e2f8\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tGrenailleuse\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tUtilis\u00e9 pour pr\u00e9parer et nettoyer les surfaces, am\u00e9liorant leur r\u00e9sistance et leur aspect.\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-26d0c30 elementor-widget-tablet__width-initial elementor-widget-mobile__width-initial elementor-widget__width-initial elementor-invisible elementor-widget elementor-widget-icon-box\" data-id=\"26d0c30\" data-element_type=\"widget\" data-settings=\"{&quot;_animation&quot;:&quot;fadeInDown&quot;}\" data-widget_type=\"icon-box.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t<div class=\"elementor-icon-box-wrapper\">\n\n\t\t\t\n\t\t\t\t\t\t<div class=\"elementor-icon-box-content\">\n\n\t\t\t\t\t\t\t\t\t<h3 class=\"elementor-icon-box-title\">\n\t\t\t\t\t\t<span  >\n\t\t\t\t\t\t\tRectifieuse\t\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/h3>\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t<p class=\"elementor-icon-box-description\">\n\t\t\t\t\t\tId\u00e9al pour obtenir des finitions pr\u00e9cises et des surfaces parfaitement planes dans diff\u00e9rents mat\u00e9riaux.\n\t\t\t\t\t<\/p>\n\t\t\t\t\n\t\t\t<\/div>\n\t\t\t\n\t\t<\/div>\n\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-11c49ae e-flex e-con-boxed e-con e-parent\" data-id=\"11c49ae\" data-element_type=\"container\" data-settings=\"{&quot;background_background&quot;:&quot;classic&quot;}\">\n\t\t\t\t\t<div class=\"e-con-inner\">\n\t\t<div class=\"elementor-element elementor-element-9c4dd5f e-con-full e-flex elementor-invisible e-con e-child\" data-id=\"9c4dd5f\" data-element_type=\"container\" data-settings=\"{&quot;animation&quot;:&quot;fadeIn&quot;}\">\n\t\t\t\t<div class=\"elementor-element elementor-element-bc69b54 elementor-widget elementor-widget-heading\" data-id=\"bc69b54\" data-element_type=\"widget\" data-widget_type=\"heading.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t<h2 class=\"elementor-heading-title elementor-size-default\">Une maintenance contr\u00f4l\u00e9e pour des performances optimales<\/h2>\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<div class=\"elementor-element elementor-element-17f4e7f elementor-widget elementor-widget-text-editor\" data-id=\"17f4e7f\" data-element_type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p>Chez Electroerosiones Navarra, nous sommes conscients que la pr\u00e9cision et la qualit\u00e9 des r\u00e9sultats d\u00e9pendent non seulement de la technologie utilis\u00e9e, mais \u00e9galement de l&#039;\u00e9tat optimal de nos machines. Pour cette raison, nous mettons en \u0153uvre un programme rigoureux de maintenance pr\u00e9ventive et corrective, r\u00e9alis\u00e9 par des techniciens sp\u00e9cialis\u00e9s.<\/p><p>Cette surveillance compl\u00e8te comprend des inspections r\u00e9guli\u00e8res, des r\u00e9glages n\u00e9cessaires et des mises \u00e0 jour logicielles, garantissant un fonctionnement efficace et fiable. Gr\u00e2ce \u00e0 cet engagement, nous \u00e9vitons les temps d\u2019arr\u00eat, prolongeons la dur\u00e9e de vie de nos \u00e9quipements et garantissons une pr\u00e9cision maximale dans chaque travail que nous r\u00e9alisons.<\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t<div class=\"elementor-element elementor-element-1c4f0d2 e-con-full e-flex e-con e-child\" data-id=\"1c4f0d2\" data-element_type=\"container\">\n\t\t\t\t<div class=\"elementor-element elementor-element-d850418 elementor-widget elementor-widget-image\" data-id=\"d850418\" data-element_type=\"widget\" data-widget_type=\"image.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"426\" height=\"473\" src=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/engranajes.png\" class=\"attachment-large size-large wp-image-4248\" alt=\"\" srcset=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/engranajes.png 426w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/engranajes-270x300.png 270w, https:\/\/elnasl.eu\/wp-content\/uploads\/2025\/02\/engranajes-11x12.png 11w\" sizes=\"(max-width: 426px) 100vw, 426px\" \/>\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Nuestras m\u00e1quinas En Electroerosiones Navarra, le damos mucha importancia al parque tecnol\u00f3gico para dar un servicio eficiente y de m\u00e1xima calidad, garantizando innovaci\u00f3n constante y adaptabilidad a las necesidades de nuestros clientes. ROBOFIL 510P\u200b Ver m\u00e1s ROBOFIL 440P Ver m\u00e1s CUT 300 MS Ver m\u00e1s CUT E350\u200b Ver m\u00e1s ONA QX3F Ver m\u00e1s STAR 64C [&hellip;]<\/p>","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-1133","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v25.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Tecnolog\u00eda - Electroerosiones Navarra<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/elnasl.eu\/fr\/maquinaria\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Tecnolog\u00eda - Electroerosiones Navarra\" \/>\n<meta property=\"og:description\" content=\"Nuestras m\u00e1quinas En Electroerosiones Navarra, le damos mucha importancia al parque tecnol\u00f3gico para dar un servicio eficiente y de m\u00e1xima calidad, garantizando innovaci\u00f3n constante y adaptabilidad a las necesidades de nuestros clientes. ROBOFIL 510P\u200b Ver m\u00e1s ROBOFIL 440P Ver m\u00e1s CUT 300 MS Ver m\u00e1s CUT E350\u200b Ver m\u00e1s ONA QX3F Ver m\u00e1s STAR 64C [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/elnasl.eu\/fr\/maquinaria\/\" \/>\n<meta property=\"og:site_name\" content=\"Electroerosiones Navarra\" \/>\n<meta property=\"article:modified_time\" content=\"2025-02-20T12:50:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI510P_RVB_HR-1.webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data1\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/elnasl.eu\/maquinaria\",\"url\":\"https:\/\/elnasl.eu\/maquinaria\",\"name\":\"Tecnolog\u00eda - Electroerosiones Navarra\",\"isPartOf\":{\"@id\":\"https:\/\/elnasl.eu\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/elnasl.eu\/maquinaria#primaryimage\"},\"image\":{\"@id\":\"https:\/\/elnasl.eu\/maquinaria#primaryimage\"},\"thumbnailUrl\":\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI510P_RVB_HR-1.webp\",\"datePublished\":\"2024-04-08T10:27:50+00:00\",\"dateModified\":\"2025-02-20T12:50:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/elnasl.eu\/maquinaria#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/elnasl.eu\/maquinaria\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/elnasl.eu\/maquinaria#primaryimage\",\"url\":\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI510P_RVB_HR-1.webp\",\"contentUrl\":\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI510P_RVB_HR-1.webp\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/elnasl.eu\/maquinaria#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/elnasl.eu\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Tecnolog\u00eda\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/elnasl.eu\/#website\",\"url\":\"https:\/\/elnasl.eu\/\",\"name\":\"Electroerosiones Navarra\",\"description\":\"25 a\u00f1os de experiencia en mecanizados por electroerosi\u00f3n.\",\"publisher\":{\"@id\":\"https:\/\/elnasl.eu\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/elnasl.eu\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/elnasl.eu\/#organization\",\"name\":\"Electroerosiones Navarra\",\"url\":\"https:\/\/elnasl.eu\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/elnasl.eu\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/elna-Recuperado-03-1.png\",\"contentUrl\":\"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/elna-Recuperado-03-1.png\",\"width\":3997,\"height\":3171,\"caption\":\"Electroerosiones Navarra\"},\"image\":{\"@id\":\"https:\/\/elnasl.eu\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Tecnolog\u00eda - Electroerosiones Navarra","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/elnasl.eu\/fr\/maquinaria\/","og_locale":"fr_FR","og_type":"article","og_title":"Tecnolog\u00eda - Electroerosiones Navarra","og_description":"Nuestras m\u00e1quinas En Electroerosiones Navarra, le damos mucha importancia al parque tecnol\u00f3gico para dar un servicio eficiente y de m\u00e1xima calidad, garantizando innovaci\u00f3n constante y adaptabilidad a las necesidades de nuestros clientes. ROBOFIL 510P\u200b Ver m\u00e1s ROBOFIL 440P Ver m\u00e1s CUT 300 MS Ver m\u00e1s CUT E350\u200b Ver m\u00e1s ONA QX3F Ver m\u00e1s STAR 64C [&hellip;]","og_url":"https:\/\/elnasl.eu\/fr\/maquinaria\/","og_site_name":"Electroerosiones Navarra","article_modified_time":"2025-02-20T12:50:02+00:00","og_image":[{"url":"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI510P_RVB_HR-1.webp","type":"","width":"","height":""}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture estim\u00e9e":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/elnasl.eu\/maquinaria","url":"https:\/\/elnasl.eu\/maquinaria","name":"Tecnolog\u00eda - Electroerosiones Navarra","isPartOf":{"@id":"https:\/\/elnasl.eu\/#website"},"primaryImageOfPage":{"@id":"https:\/\/elnasl.eu\/maquinaria#primaryimage"},"image":{"@id":"https:\/\/elnasl.eu\/maquinaria#primaryimage"},"thumbnailUrl":"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI510P_RVB_HR-1.webp","datePublished":"2024-04-08T10:27:50+00:00","dateModified":"2025-02-20T12:50:02+00:00","breadcrumb":{"@id":"https:\/\/elnasl.eu\/maquinaria#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/elnasl.eu\/maquinaria"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/elnasl.eu\/maquinaria#primaryimage","url":"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI510P_RVB_HR-1.webp","contentUrl":"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/FI510P_RVB_HR-1.webp"},{"@type":"BreadcrumbList","@id":"https:\/\/elnasl.eu\/maquinaria#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/elnasl.eu\/"},{"@type":"ListItem","position":2,"name":"Tecnolog\u00eda"}]},{"@type":"WebSite","@id":"https:\/\/elnasl.eu\/#website","url":"https:\/\/elnasl.eu\/","name":"Electroerosiones Navarra","description":"25 a\u00f1os de experiencia en mecanizados por electroerosi\u00f3n.","publisher":{"@id":"https:\/\/elnasl.eu\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/elnasl.eu\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/elnasl.eu\/#organization","name":"Electroerosiones Navarra","url":"https:\/\/elnasl.eu\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/elnasl.eu\/#\/schema\/logo\/image\/","url":"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/elna-Recuperado-03-1.png","contentUrl":"https:\/\/elnasl.eu\/wp-content\/uploads\/2024\/04\/elna-Recuperado-03-1.png","width":3997,"height":3171,"caption":"Electroerosiones Navarra"},"image":{"@id":"https:\/\/elnasl.eu\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/elnasl.eu\/fr\/wp-json\/wp\/v2\/pages\/1133","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/elnasl.eu\/fr\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/elnasl.eu\/fr\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/elnasl.eu\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/elnasl.eu\/fr\/wp-json\/wp\/v2\/comments?post=1133"}],"version-history":[{"count":245,"href":"https:\/\/elnasl.eu\/fr\/wp-json\/wp\/v2\/pages\/1133\/revisions"}],"predecessor-version":[{"id":4254,"href":"https:\/\/elnasl.eu\/fr\/wp-json\/wp\/v2\/pages\/1133\/revisions\/4254"}],"wp:attachment":[{"href":"https:\/\/elnasl.eu\/fr\/wp-json\/wp\/v2\/media?parent=1133"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}